{"id":7925,"date":"2019-01-25T13:41:25","date_gmt":"2019-01-25T18:41:25","guid":{"rendered":"http:\/\/www.jjcardinal.ca\/?p=7925"},"modified":"2019-06-19T13:46:03","modified_gmt":"2019-06-19T17:46:03","slug":"mr-andre-therrien","status":"publish","type":"post","link":"https:\/\/jjcardinal.ca\/en\/mr-andre-therrien\/","title":{"rendered":"Mr. Andr\u00e9 Therrien"},"content":{"rendered":"<p><strong>Passed away \u00a0on\u00a0January 25th, 2019\u00a0 at the age of\u00a067 years old<\/strong><\/p>\n<hr \/>\n<div class=\"texte\">\n<div class=\"texte\">\n<p>Le 25 janvier est d\u00e9c\u00e9d\u00e9 Andr\u00e9 Therrien. Andr\u00e9 \u00e9tait le fils de feu Fran\u00e7ois-Xavier Therrien et de feu Henriette Pelletier.<\/p>\n<p>Il laisse dans le deuil sa femme depuis plus de 30 ans Line Laberge, qui l&#8217;a accompagn\u00e9 tout au long de sa maladie avec tendresse et affection, sa fille Cathy Therrien (Jean M\u00e9nard), ses s\u0153urs et fr\u00e8res Micheline, Francine, Diane, Jocelyne, feu Robert (Lise), Richard et neveux et ni\u00e8ces, sa belle-famille Annette, G\u00e9rard, feu Francine, Denis et Charles-Edouard Laberge ainsi que parents et amis.<\/p>\n<p>Andr\u00e9 \u00e9tait un grand p\u00eacheur, sport qu&#8217;il a pratiqu\u00e9 surtout dans la r\u00e9gion de Charlevoix qu&#8217;il aimait particuli\u00e8rement. Cuisinier \u00e9m\u00e9rite et homme de maison, il \u00e9tait aussi social et bavard avec les personnes qu&#8217;il rencontrait et avec qui il aimait \u00e9changer, discuter et rire.<\/p>\n<p>Sa femme tient \u00e0 remercier tout le personnel et les b\u00e9n\u00e9voles de l&#8217;oncologie de l&#8217;h\u00f4pital g\u00e9n\u00e9ral du Lakeshore, le personnel en soins \u00e0 domicile du CLSC de Vaudreuil-Dorion ainsi que tout le personnel et les b\u00e9n\u00e9voles de la Maison des soins palliatifs de Vaudreuil-Soulanges.<\/p>\n<p>La famille recevra les condol\u00e9ances \u00e0 la R\u00e9sidence Fun\u00e9raire J.J. Cardinal, 2125 rue Notre-Dame, Lachine (www.jjcardinal.ca 514-639-1511) le dimanche 3 f\u00e9vrier de 14h-16h suivi du service fun\u00e9raire dans la chapelle de la r\u00e9sidence.<\/p>\n<p>Vos t\u00e9moignages de sympathie peuvent se traduire par un don \u00e0 la Fondation Maison de soins palliatifs de Vaudreuil-Soulanges ou la Fondation de l&#8217;h\u00f4pital g\u00e9n\u00e9ral du Lakeshore.<\/p>\n<\/div>\n<h3 class=\"menu-action-bar\">DONATE<\/h3>\n<p class=\"menu-action-bar\">&#8211;\u00a0<a href=\"https:\/\/www.canadahelps.org\/dn\/15276\" target=\"_blank\" rel=\"noopener\">Vaudreuil Soulanges Palliative Care Residence Foundation<\/a><\/p>\n<div class=\"spacing-top-40px\">\n<h3>R\u00c9SIDENCE FUN\u00c9RAIRE J.J. CARDINAL<\/h3>\n<p>2125, rue Notre-Dame, Lachine (Qu\u00e9bec)\u00a0\u00a0H8S 2G5<\/p>\n<p>Tel.:\u00a0514-639-1511\u00a0|\u00a0Fax:\u00a0514-639-1516\u00a0|\u00a0Email:\u00a0<a href=\"mailto:info@jjcardinal.ca\">info@jjcardinal.ca<\/a><\/p>\n<p class=\"links\"><a href=\"http:\/\/goo.gl\/maps\/6TF2f\" target=\"_blank\" rel=\"noopener\">Driving directions<\/a>\u00a0|\u00a0<a href=\"http:\/\/www.meteomedia.com\/weather\/caqc0281\" target=\"_blank\" rel=\"noopener\">Weather forecasts<\/a><\/p>\n<\/div>\n<\/div>\n<div class=\"spacing-top-40px\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Passed away \u00a0on\u00a0January 25th, 2019\u00a0 at the age of\u00a067 years old Le 25 janvier est d\u00e9c\u00e9d\u00e9 Andr\u00e9 Therrien. Andr\u00e9 \u00e9tait le fils de feu Fran\u00e7ois-Xavier Therrien et de feu Henriette Pelletier. Il laisse dans le deuil sa femme depuis plus de 30 ans Line Laberge, qui l&#8217;a accompagn\u00e9 tout au long de sa maladie avec [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":5148,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[68],"tags":[],"class_list":["post-7925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-obituaries"],"_links":{"self":[{"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/posts\/7925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/comments?post=7925"}],"version-history":[{"count":0,"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/posts\/7925\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/media\/5148"}],"wp:attachment":[{"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/media?parent=7925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/categories?post=7925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/tags?post=7925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}