{"id":9213,"date":"2019-08-20T12:58:56","date_gmt":"2019-08-20T16:58:56","guid":{"rendered":"http:\/\/www.jjcardinal.ca\/?p=9213"},"modified":"2019-10-30T13:00:48","modified_gmt":"2019-10-30T17:00:48","slug":"mrs-madeleine-lauzon-chantelois","status":"publish","type":"post","link":"https:\/\/jjcardinal.ca\/en\/mrs-madeleine-lauzon-chantelois\/","title":{"rendered":"Mrs Madeleine Lauzon Chantelois"},"content":{"rendered":"<p class=\"date-deces\"><strong>Passed away on\u00a0August 20th, 2019 at the age of\u00a091 years old<\/strong><\/p>\n<hr \/>\n<div>\n<div class=\"texte\">\n<div class=\"texte\">\n<p>\u00c0 Lachine le 20 ao\u00fbt 2019 est d\u00e9c\u00e9d\u00e9e Madeleine Lauzon Chantelois \u00e0 l\u2019\u00e2ge de 91 ans et 7 mois. Elle \u00e9tait l\u2019\u00e9pouse de feu Roger Chantelois, fille de feu Jean-Baptiste Lauzon et de feu L\u00e9onie Charron. Elle \u00e9tait la cousine de Mme Aline Beaulne-Brunet, de Claude Charron, ancien ministre du gouvernement de M. Ren\u00e9 L\u00e9vesque du Qu\u00e9bec, de Normand Larente, et de feu Maurice Lauzon. Elle laisse \u00e9galement dans le deuil son beau-fr\u00e8re Pierre Chantelois, plusieurs neveux et ni\u00e8ces de la famille Chantelois, ses amies des \u00c9tats-Unis, Mme C\u00e9cile Desforges-Pinder , Susan Pinder et Doris Steinhardt ainsi que ses ami(e)s les B\u00e9n\u00e9voles du Centre Hospitalier de Lachine et du Pavillon Camille\u2013Lefebvre. Elle \u00e9tait membre des Auxiliaires-B\u00e9n\u00e9voles du Centre Hospitalier de Lachine pendant 44 ans dont 28 ans comme pr\u00e9sidente. Elle fut d\u00e9cor\u00e9e par M. le maire Claude Dauphin le 9 octobre 2015 pour son implication aupr\u00e8s des malades du Centre Hospitalier de Lachine et des r\u00e9sidents du Pavillon Camille Lefebvre.<\/p>\n<p>Elle sera expos\u00e9e \u00e0 la R\u00e9sidence J.J. Cardinal au 2125 Notre-Dame Lachine le vendredi 23 ao\u00fbt de 14h \u00e0 17h et de 19h \u00e0 21h. Les fun\u00e9railles auront lieu samedi le 24 ao\u00fbt en l\u2019\u00e9glise des Saints-Anges-Gardiens, 1400 Blvd. St -Joseph Lachine \u00e0 10 heures. La c\u00e9l\u00e9bration sera pr\u00e9sid\u00e9e par le P\u00e8re Louis Turcotte c.j.m., aum\u00f4nier du Centre Hospitalier de Lachine et du Pavillon Camille-Lefebvre. Elle sera incin\u00e9r\u00e9e et l\u2019urne sera d\u00e9pos\u00e9e dans la niche avec son \u00e9poux Roger au columbarium de la paroisse des Saints-Anges.<\/p>\n<p>Un MERCI sp\u00e9cial au Dre Laurie Musgrave, directrice des soins palliatifs de l\u2019h\u00f4pital de Lachine et au Dre Genevi\u00e8ve Chaput et \u00e0 Mme Faiza Anine, infirmi\u00e8re-pivot en oncologie \u00e0 l\u2019h\u00f4pital de Lachine. Un merci \u00e0 ses amies Suzanne Baillargeon, Denise B\u00e9langer et \u00e0 Lyne Couillard pour leur aide et leur amiti\u00e9 sinc\u00e8re. Un MERCI aux pr\u00e9pos\u00e9es de l\u2019unit\u00e9 de soins B2 du Belv\u00e9d\u00e8re pour leur gentillesse, aux m\u00e9decins et au personnel des soins palliatifs du Centre Hospitalier de Lachine pour leur compassion et leur humanit\u00e9 dans les derniers moments de sa vie.<\/p>\n<p>En guise de sympathies, des dons \u00e0 la fondation du Centre Hospitalier de Lachine seraient appr\u00e9ci\u00e9s.<\/p>\n<p>Une pri\u00e8re de chacun de vous serait appr\u00e9ci\u00e9e pour lui faciliter ce dernier voyage qu\u2019elle a entrepris. Nous nous en remettons au Seigneur pour qu\u2019Il lui assigne une place de choix dans son Paradis \u00e0 celle dont le B\u00c9N\u00c9VOLAT, envers les malades et les plus d\u00e9munis, \u00e9tait toute sa vie.<\/p>\n<p>TOUTES LES S\u00c9PARATIONS DU TEMPS NE SONT QU\u2019UN RENDEZ \u2013VOUS POUR L\u2019\u00c9TERNIT\u00c9.<\/p>\n<\/div>\n<h3 class=\"menu-action-bar\">DONATE<\/h3>\n<p class=\"menu-action-bar\">&#8211;\u00a0<a href=\"http:\/\/lachinehospitalfoundation.org\/make-a-donation\/how-to-make-a-donation\/\" target=\"_blank\" rel=\"noopener\">The Lachine Hospital Foundation<\/a><\/p>\n<div class=\"spacing-top-40px\">\n<h3>R\u00c9SIDENCE FUN\u00c9RAIRE J.J. CARDINAL<\/h3>\n<p>2125, rue Notre-Dame, Lachine (Qu\u00e9bec)\u00a0\u00a0H8S 2G5<\/p>\n<p>Tel.:\u00a0514-639-1511\u00a0|\u00a0Fax:\u00a0514-639-1516\u00a0|\u00a0Email:\u00a0<a href=\"mailto:info@jjcardinal.ca\">info@jjcardinal.ca<\/a><\/p>\n<p class=\"links\"><a href=\"https:\/\/goo.gl\/maps\/6TF2f\" target=\"_blank\" rel=\"noopener\">Driving directions<\/a>\u00a0|\u00a0<a href=\"http:\/\/www.meteomedia.com\/weather\/caqc0281\" target=\"_blank\" rel=\"noopener\">Weather forecasts<\/a><\/p>\n<\/div>\n<\/div>\n<div class=\"spacing-top-40px\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Passed away on\u00a0August 20th, 2019 at the age of\u00a091 years old \u00c0 Lachine le 20 ao\u00fbt 2019 est d\u00e9c\u00e9d\u00e9e Madeleine Lauzon Chantelois \u00e0 l\u2019\u00e2ge de 91 ans et 7 mois. Elle \u00e9tait l\u2019\u00e9pouse de feu Roger Chantelois, fille de feu Jean-Baptiste Lauzon et de feu L\u00e9onie Charron. Elle \u00e9tait la cousine de Mme Aline Beaulne-Brunet, [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":9211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[68],"tags":[],"class_list":["post-9213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-obituaries"],"_links":{"self":[{"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/posts\/9213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/comments?post=9213"}],"version-history":[{"count":0,"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/posts\/9213\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/media\/9211"}],"wp:attachment":[{"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/media?parent=9213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/categories?post=9213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jjcardinal.ca\/en\/wp-json\/wp\/v2\/tags?post=9213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}